{"id":3092,"date":"2026-04-14T17:58:43","date_gmt":"2026-04-14T15:58:43","guid":{"rendered":"https:\/\/www.solatiafarm.com\/?post_type=product&#038;p=3092"},"modified":"2026-04-27T15:12:30","modified_gmt":"2026-04-27T13:12:30","slug":"deluxe-experience-box-set-copia","status":"publish","type":"product","link":"https:\/\/www.solatiafarm.com\/en\/prodotto\/deluxe-experience-box-set-copia\/","title":{"rendered":"Discovery Box Set"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; left_padding_desktop=&#8221;2%&#8221; constrain_group_2=&#8221;yes&#8221; right_padding_desktop=&#8221;2%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1902&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;5%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;5%&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_responsive_text inherited_font_style=&#8221;default&#8221; text_color=&#8221;#0c0c0c&#8221; text_direction=&#8221;default&#8221; font_size_desktop=&#8221;4vw&#8221; font_line_height=&#8221;1.1&#8243;]\n<h2>All the news from the Solat\u00eca Farm world.<\/h2>\n[\/nectar_responsive_text][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; top_padding=&#8221;2%&#8221; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;2%&#8221; text_align=&#8221;left&#8221; row_position=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; pointer_events=&#8221;all&#8221;][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;1px&#8221; column_border_color=&#8221;#c9c9c9&#8243; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][recent_posts style=&#8221;classic_enhanced&#8221; color_scheme=&#8221;light&#8221; columns=&#8221;1&#8243; category=&#8221;radici&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; blog_remove_post_date=&#8221;true&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; blog_remove_post_nectar_love=&#8221;true&#8221; posts_per_page=&#8221;1&#8243;][\/vc_column_inner][vc_column_inner column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; overflow=&#8221;visible&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][recent_posts style=&#8221;minimal&#8221; columns=&#8221;2&#8243; category=&#8221;manifestazioni,radici&#8221; order=&#8221;DESC&#8221; orderby=&#8221;date&#8221; blog_remove_post_date=&#8221;true&#8221; blog_remove_post_author=&#8221;true&#8221; blog_remove_post_comment_number=&#8221;true&#8221; posts_per_page=&#8221;4&#8243; post_offset=&#8221;1&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<h3>The most immediate way to enter the world of Solat\u00eca Farm.<\/h3>\n<p data-start=\"835\" data-end=\"1078\">Gift box with one bottle of <strong>Radici 250 ml<\/strong> and one bottle of <strong>Autentico 250 ml<\/strong> in a colorful and contemporary designed package. An ideal proposal for a quality thought, a first tasting or an elegant and affordable gift. <\/p>\n<p data-start=\"1080\" data-end=\"1370\">Inside you will find two interpretations of the Itrana cultivar. <strong data-start=\"1141\" data-end=\"1209\">Radici, Colline Pontine Organic PDO Extra Virgin Olive Oil<\/strong>, with an elegant and harmonious profile. <strong data-start=\"1245\" data-end=\"1306\">Autentico, Colline Pontine PDO Extra Virgin Olive Oil<\/strong>, fresh and aromatic, with vegetal notes and pleasant persistence.<\/p>\n<p data-start=\"1372\" data-end=\"1418\">An invitation to discovery, signed Solat\u00eca Farm.<\/p>\n<h3><strong>Content:<\/strong><\/h3>\n<ul>\n<li data-start=\"206\" data-end=\"493\">1 Bottle of Radici 250 ml<\/li>\n<li data-start=\"206\" data-end=\"493\">1 Bottle of Autentico 250 ml<\/li>\n<li data-start=\"206\" data-end=\"493\">Brochure dedicated to the history of the company<\/li>\n<li data-start=\"206\" data-end=\"493\">Deluxe Gift Box Set<\/li>\n<\/ul>\n<h3><strong>Conservation:<\/strong><\/h3>\n<p>Store Bottle in a cool, dry place, away from direct light and heat sources.<\/p>\n","protected":false},"featured_media":3096,"template":"","meta":{"_monsterinsights_skip_tracking":false},"product_brand":[],"product_cat":[141,144],"product_tag":[176,177,86,178,87],"class_list":["post-3092","product","type-product","status-publish","has-post-thumbnail","product_cat-pdo","product_cat-premium-en","product_tag-authentic","product_tag-gift","product_tag-premium-en","product_tag-prestige","product_tag-roots","pa_contenitore-bag-in-box-en","pa_litri-55","_wholesalex wsx-wholesalex-product","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":300,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","_links":{"self":[{"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/product\/3092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/media\/3096"}],"wp:attachment":[{"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/media?parent=3092"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/product_brand?post=3092"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/product_cat?post=3092"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.solatiafarm.com\/en\/wp-json\/wp\/v2\/product_tag?post=3092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}